{"id":25,"date":"2017-03-14T12:01:13","date_gmt":"2017-03-14T11:01:13","guid":{"rendered":"http:\/\/www.chronoflex.ch\/?page_id=25"},"modified":"2017-04-28T10:08:09","modified_gmt":"2017-04-28T08:08:09","slug":"conditions-generales-de-reparation","status":"publish","type":"page","link":"https:\/\/www.chronoflex.ch\/fr\/conditions-generales-de-reparation\/","title":{"rendered":"Conditions g\u00e9n\u00e9rales de r\u00e9paration"},"content":{"rendered":"<ol>\n<li><b> G\u00c9N\u00c9RALIT\u00c9S<\/b><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Les conditions suivantes s\u2019appliquent \u00e0 toutes les livraisons et \u00e0 tous les travaux du fournisseur r\u00e9sultant d\u2019un contrat de vente ou d\u2019entreprise. D\u2019\u00e9ventuelles d\u00e9rogations ne sont valables que si elles ont \u00e9t\u00e9 convenues par \u00e9crit entre les parties contractantes.<\/span><\/p>\n<ol start=\"2\">\n<li><b> OFFRE<\/b><\/li>\n<li><span style=\"font-weight: 400;\">a) Bases techniques<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Les caract\u00e9ristiques techniques figurant dans l\u2019offre font foi. Toute divergence importante par rapport aux renseignements contenus dans des catalogues, sur des dessins et photos doit \u00eatre communiqu\u00e9e au client lors de la remise de l\u2019offre.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tous les documents restent la propri\u00e9t\u00e9 du fournisseur. Il n\u2019est permis, ni de les photocopier ni de les polycopier, ni de les mettre \u00e0 disposition de tiers, ni de les utiliser pour construire soi-m\u00eame les mat\u00e9riels en question. Ils doivent \u00eatre restitu\u00e9s sur demande.<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\">b) R\u00e9serve de vente<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Jusqu\u2019\u00e0 la conclusion d\u00e9finitive du contrat avec le client, le fournisseur peut en tout temps vendre \u00e0 des tiers le mat\u00e9riel qu\u2019il a offert \u00e0 celui-ci.<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\">c) Frais de projet<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Si le client a charg\u00e9 le fournisseur d\u2019\u00e9tablir un projet, mais qu\u2019il ne lui en confie pas l\u2019ex\u00e9cution apr\u00e8s avoir re\u00e7u l\u2019offre, le fournisseur a la facult\u00e9 de lui demander le paiement des frais d\u2019\u00e9tablissement du projet selon le tarif SIA. Cependant, cette disposition ne s\u2019applique pas \u00e0 des investigations de base en vue de l\u2019\u00e9laboration de l\u2019offre.<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\">d) Travaux d\u2019implantation<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Toutes les op\u00e9rations relatives \u00e0 l\u2019implantation du mat\u00e9riel \u00e0 livrer (choix du site de la machine, \u00e9tude du terrain, fourniture des plans de construction et obtention des autorisations requises, construction des fondations y compris voies de roulement et mise en place des installations \u00e9lectriques, adduction d\u2019eau, am\u00e9nagement d\u2019une voie d\u2019acc\u00e8s ad\u00e9quate, pr\u00e9paration d\u2019une aire de travail d\u2019une portance suffisante pour d\u2019\u00e9ventuels entreposages temporaires et pr\u00e9montages, fourniture des engins de levage requis, approvisionnement en consommables tels combustibles, air comprim\u00e9, et ex\u00e9cution \u00e9ventuelle d\u2019autres travaux de construction) incombent au client et ne font pas partie de l\u2019offre.<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\">e) Utilisation<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Les instructions d\u2019utilisation et d\u2019entretien du constructeur et\/ou du fournisseur, les directives pour une utilisation ad\u00e9quate ainsi que les charges admises doivent \u00eatre strictement respect\u00e9es.<\/span><\/p>\n<ol start=\"3\">\n<li><b> CONCLUSION DU CONTRAT<\/b><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Les contrats de vente et d\u2019entreprise ne sont ent\u00e9rin\u00e9s qu\u2019apr\u00e8s signature par les deux parties. Le fournisseur n\u2019est li\u00e9 par les engagements de ses voyageurs de commerce que s\u2019il ne les d\u00e9nonce pas par \u00e9crit dans un d\u00e9lai de 10 jours ouvrables \u00e0 dater de la conclusion du contrat.<\/span><\/p>\n<ol start=\"4\">\n<li><b> PRIX<\/b><\/li>\n<li><span style=\"font-weight: 400;\">a) Les prix s\u2019entendent pour livraison \u00e0 partir de l\u2019entrep\u00f4t du fournisseur, mat\u00e9riel charg\u00e9 sur le v\u00e9hicule de transport.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">b) Toute augmentation de prix ult\u00e9rieure \u00e0 la conclusion d\u00e9finitive du contrat ne pourra \u00eatre r\u00e9percut\u00e9e sur le client qu\u2019avec l\u2019accord de celui-ci.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">c) Les commandes pass\u00e9es dans le cadre d\u2019un contrat d\u2019entreprise feront l\u2019objet d\u2019un accord s\u00e9par\u00e9 (monnaie, rench\u00e9rissement, transport, emballage, assurance, douane, imp\u00f4ts et taxes).<\/span><\/li>\n<li><b> LIVRAISON<\/b><\/li>\n<li><span style=\"font-weight: 400;\">a) D\u00e9lai de livraison<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Le d\u00e9lai de livraison court \u00e0 partir de la conclusion du contrat, mais au plus t\u00f4t apr\u00e8s r\u00e9ception de toutes les donn\u00e9es et documents \u00e0 fournir par le client ainsi que des acomptes \u00e0 verser \u00e9ventuellement. Le d\u00e9lai est fix\u00e9 en tenant compte de la situation existant lors de la signature du contrat et a force obligatoire. Il est susceptible d\u2019\u00eatre prolong\u00e9 en cas d\u2019\u00e9v\u00e9nements impr\u00e9vus, ind\u00e9pendants de la volont\u00e9 du fournisseur (p. ex. force majeure, difficult\u00e9s dans l\u2019approvisionnement en mat\u00e9riaux, interruptions d\u2019exploitation etc.). De plus, il est suspendu tant que le client n\u2019effectue pas les paiements convenus aux \u00e9ch\u00e9ances pr\u00e9vues. Si le client subit un pr\u00e9judice par suite d\u2019un retard imputable au fournisseur, celui-ci a la facult\u00e9, \u00e0 l\u2019exclusion de toute autre revendication, apr\u00e8s un d\u00e9lai de gr\u00e2ce de 2 semaines, de r\u00e9clamer une indemnit\u00e9 de retard. Celle-ci s\u2019\u00e9l\u00e8ve \u00e0 1\/2% pour chaque semaine r\u00e9volue de retard, sans cependant pouvoir exc\u00e9der 5% de la valeur totale de la partie de la fourniture n\u2019ayant pu \u00eatre utilis\u00e9e en temps voulu ou comme pr\u00e9vu ou, dans le cas d\u2019un contrat d\u2019entreprise, de la valeur de l\u2019ouvrage. Si apr\u00e8s \u00e9coulement du temps correspondant aux 5% d\u2019indemnisation maximale le fournisseur n\u2019est toujours pas en mesure de livrer le mat\u00e9riel comme convenu pour une raison qui lui est imputable, le client est en droit de r\u00e9silier le contrat apr\u00e8s avoir accord\u00e9 au fournisseur un dernier d\u00e9lai convenable. Les parties sont libres de convenir dans le cadre des contrats de vente\/d\u2019entreprise individuels des r\u00e8gles bonifiant\/p\u00e9nalisant toute modification des d\u00e9lais de livraison.<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\">b) Transport<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Les frais de transport sont \u00e0 la charge du client. L\u2019exp\u00e9dition se fait aux risques et p\u00e9rils du client, m\u00eame dans le cas d\u2019une livraison franco de port. Le risque est transf\u00e9r\u00e9 au client d\u00e8s que l\u2019envoi est mis \u00e0 la disposition du voiturier, du commissionnaire-exp\u00e9diteur ou du client, sur le lieu d\u2019entreposage du fournisseur. Si, \u00e0 la r\u00e9ception de la marchandise, le client constate des dommages ou des d\u00e9fauts, il est tenu de les signaler imm\u00e9diatement au voiturier ou \u00e0 commissionnaire-exp\u00e9diteur du fournisseur et \u00e0 l\u2019assurance. Si cela s\u2019av\u00e8re n\u00e9cessaire pour l\u2019\u00e9tablissement des preuves, le client est tenu de faire dresser un proc\u00e8s verbal sign\u00e9 par les intervenants. Le nombre de pi\u00e8ces livr\u00e9es doit \u00eatre v\u00e9rifi\u00e9 d\u2019apr\u00e8s les bulletins de livraison. Si aucune r\u00e9clamation \u00e9crite ne parvient au fournisseur dans un d\u00e9lai de 8 jours ouvrables, l\u2019envoi est r\u00e9put\u00e9 accept\u00e9. Des contestations ult\u00e9rieures ne seront prises en consid\u00e9ration que si, au moment de la livraison, les d\u00e9fauts n\u2019\u00e9taient pas perceptibles, malgr\u00e9 une v\u00e9rification consciencieuse et si le client pr\u00e9sente par \u00e9crit une r\u00e9clamation dans un d\u00e9lai d\u2019une semaine apr\u00e8s avoir constat\u00e9 les d\u00e9fauts en question, mais au plus tard avant l\u2019\u00e9ch\u00e9ance de la garantie.<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\">c) Entreposage<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Si la mise \u00e0 la disposition du mat\u00e9riel command\u00e9 a \u00e9t\u00e9 notifi\u00e9e au client et ce mat\u00e9riel ne peut pas \u00eatre livr\u00e9 dans les d\u00e9lais pr\u00e9vus, sans qu\u2019il y ait faute du fournisseur, il sera entrepos\u00e9 aux frais et aux risques du client chez le fournisseur ou chez un tiers.<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\">d) Montage et d\u00e9montage<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Le fournisseur ne se charge du montage ou du d\u00e9montage du mat\u00e9riel livr\u00e9 que s\u2019il en a \u00e9t\u00e9 convenu express\u00e9ment. Dans d\u2019autres cas, il met des monteurs \u00e0 la disposition du client, si celui-ci en fait la demande, moyennant facturation des heures de d\u00e9placement, de travail et d\u2019attente, ainsi que des frais de voyage et d\u2019h\u00e9bergement selon les tarifs du fournisseur en vigueur.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si les monteurs ne peuvent commencer leur travail ou le poursuivre sans qu\u2019il y ait faute de leur part ou du fournisseur, tous les frais suppl\u00e9mentaires en d\u00e9coulant sont \u00e0 la charge du client, m\u00eame si une somme forfaitaire a \u00e9t\u00e9 convenue pour les travaux de montage et de d\u00e9montage. Il incombe \u00e9galement au client de fournir, comme convenu et en temps utile, le personnel auxiliaire et l\u2019\u00e9quipement de montage n\u00e9cessaire (p.ex. grues). Dans la mesure o\u00f9 le client est tenu de mettre des monteurs ou des auxiliaires \u00e0 la disposition du fournisseur, les salaires et frais, prestations sociales et primes d\u2019assurance etc. de ces derniers sont \u00e0 la charge du client.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Les temps de montage ou de d\u00e9montage indiqu\u00e9s par le fournisseur charg\u00e9 d\u2019effectuer ces op\u00e9rations ont force obligatoire. Des circonstances dont il n\u2019est pas responsable, par exemple obstacles, cas de force majeure, intemp\u00e9ries, pr\u00e9paration de chantier non conforme au contrat etc. peuvent entra\u00eener une prolongation des d\u00e9lais. L\u2019inobservation des temps de montage et de d\u00e9montage pour les motifs \u00e9num\u00e9r\u00e9s ci-dessus ne donne au client ni le droit d\u2019annuler sa commande, ni \u00e0 r\u00e9clamer des dommages-int\u00e9r\u00eats.<\/span><\/p>\n<ol start=\"6\">\n<li><b> CONDITIONS DE PAIEMENT<\/b><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Sauf stipulation contraire, les conditions de paiement sont les suivantes:<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\">a) pour les contrats de vente, livraisons de pi\u00e8ces de rechange, r\u00e9parations 30 jours apr\u00e8s l\u2019envoi de la facture, net de toute d\u00e9duction.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">b) pour les contrats d\u2019entreprise<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">1\/3 \u00e0 la conclusion du contrat<\/span><\/p>\n<p><span style=\"font-weight: 400;\">1\/3 lors de l\u2019avis de la mise \u00e0 disposition du mat\u00e9riel au client<\/span><\/p>\n<p><span style=\"font-weight: 400;\">1\/3 30 jours apr\u00e8s que le mat\u00e9riel est pr\u00eat \u00e0 \u00eatre mis en service.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Les paiements sont toujours \u00e0 effectuer sans frais \u00e0 charge du fournisseur.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ils doivent \u00eatre effectu\u00e9s m\u00eame s\u2019il est n\u00e9cessaire de proc\u00e9der \u00e0 des travaux suppl\u00e9mentaires sur le mat\u00e9riel livr\u00e9 ou de remplacer des pi\u00e8ces ou si, pour des motifs imputables au client, le mat\u00e9riel ne peut \u00eatre livr\u00e9 dans les d\u00e9lais. Cependant, en cas de livraison erron\u00e9e ou de d\u00e9fauts graves imputables au fournisseur et excluant une mise en service du mat\u00e9riel, le dernier tiers du paiement ne sera exigible qu\u2019apr\u00e8s r\u00e9ception du mat\u00e9riel dans l\u2019\u00e9tat convenu contractuellement ou apr\u00e8s \u00e9limination des d\u00e9fauts en question.<\/span><\/p>\n<ol start=\"7\">\n<li><b> DEMEURE DU CLIENT<\/b><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Les cr\u00e9ances qui n\u2019ont pas \u00e9t\u00e9 r\u00e9gl\u00e9es dans les d\u00e9lais pr\u00e9vus deviennent imm\u00e9diatement exigibles. Le montant d\u00fb sera major\u00e9 d\u2019un int\u00e9r\u00eat moratoire \u00e0 dater de l\u2019\u00e9ch\u00e9ance sans qu\u2019un avis pr\u00e9alable soit n\u00e9cessaire, cet int\u00e9r\u00eat \u00e9tant normalement de 1% sup\u00e9rieur au taux d\u2019int\u00e9r\u00eat usuel des banques sur les comptes courants. Si des acomptes ne sont pas vers\u00e9s dans les 30 jours qui suivent leur \u00e9ch\u00e9ance, la totalit\u00e9 du montant restant devient exigible. En cas de livraisons erron\u00e9es ou de d\u00e9fauts graves imputables au fournisseur et excluant une mise en service du mat\u00e9riel, le client a la facult\u00e9 d\u2019exiger un report des d\u00e9lais de paiement. En cas de demeure du client le fournisseur se r\u00e9serve express\u00e9ment le droit de se d\u00e9partir du contrat et d\u2019exiger la restitution du mat\u00e9riel livr\u00e9. En cas de vente \u00e0 temp\u00e9rament, le fournisseur est habilit\u00e9 \u00e0 exiger le paiement du solde du prix d\u2019achat en une seule fois ou \u00e0 se d\u00e9partir du contrat. Le fournisseur a la facult\u00e9 de se d\u00e9partir du contrat et d\u2019exiger la restitution du mat\u00e9riel livr\u00e9 m\u00eame si l\u2019acheteur est en retard de paiement pour le dernier acompte.<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\">a) Si le fournisseur choisit de se d\u00e9partir du contrat, le client est tenu de lui fournir les prestations<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">suivantes, outre la restitution imm\u00e9diate du mat\u00e9riel qui aurait d\u00e9j\u00e0 \u00e9t\u00e9 livr\u00e9:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u2013 le paiement d\u2019un loyer \u00e9gal \u00e0 5% du prix convenu pour chaque mois r\u00e9volu ou commenc\u00e9, \u00e0 dater de la livraison jusqu\u2019\u00e0 la restitution du mat\u00e9riel livr\u00e9.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u2013 le versement de dommages-int\u00e9r\u00eats pour une \u00e9ventuelle usure anormale ou une d\u00e9t\u00e9rioration du mat\u00e9riel livr\u00e9;<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u2013 le paiement des frais de d\u00e9montage, de transport et d\u2019assurance pour le retour du mat\u00e9riel livr\u00e9, ainsi que le remboursement de tous autres frais \u00e9ventuels r\u00e9sultant de ces op\u00e9rations. Le client est redevable de ces prestations m\u00eame si aucune faute ne peut lui \u00eatre imput\u00e9e.<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\">b) Si le pr\u00e9judice subi par le fournisseur d\u00e9passe les prestations mentionn\u00e9es \u00e0 l\u2019alin\u00e9a a), le client doit lui rembourser la diff\u00e9rence, \u00e0 moins qu\u2019il ne d\u00e9montre qu\u2019il n\u2019y pas eu faute de sa part.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">c) Les dispositions qui pr\u00e9c\u00e8dent seront appliqu\u00e9es par analogie \u00e0 tous les autres cas d\u2019inex\u00e9cution du contrat par le client, par ex. s\u2019il omet de prendre livraison du mat\u00e9riel command\u00e9.<\/span><\/li>\n<li><b> R\u00c9SERVE DE PROPRI\u00c9T\u00c9<\/b><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Le mat\u00e9riel livr\u00e9 demeure la propri\u00e9t\u00e9 du fournisseur jusqu\u2019au moment o\u00f9 le prix convenu, y compris tous les frais et int\u00e9r\u00eats additionnels, a \u00e9t\u00e9 int\u00e9gralement pay\u00e9. Jusqu\u2019\u00e0 cette date, il ne pourra ni \u00eatre mis en gage, ni vendu ni lou\u00e9 sans l\u2019autorisation pr\u00e9alable du fournisseur. Le client demeure n\u00e9anmoins responsable du mat\u00e9riel. Le fournisseur est habilit\u00e9 \u00e0 faire inscrire la r\u00e9serve de propri\u00e9t\u00e9 au registre des r\u00e9serves de propri\u00e9t\u00e9 du domicile du client.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En outre, le client est tenu d\u2019informer imm\u00e9diatement le fournisseur de tout changement de domicile ou de si\u00e8ge social.<\/span><\/p>\n<ol start=\"9\">\n<li><b> ASSURANCE<\/b><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Le client est tenu de conclure toutes les assurances n\u00e9cessaires pour le mat\u00e9riel non ou non enti\u00e8rement pay\u00e9, prenant effet \u00e0 la date de transfert du risque et couvrant, par exemple, les risques suivants: vol, incendie, explosion, catastrophes naturelles, transport, bris de machine et\/ou assurance tous risques machine et montage. Il c\u00e8de au fournisseur les prestations auxquelles ces assurances lui donnent droit. Si le client n\u2019est pas en mesure de prouver la conclusion des assurances n\u00e9cessaires, le fournisseur peut contracter lui-m\u00eame ces assurances aux frais du client. Le client doit annoncer imm\u00e9diatement tout sinistre au fournisseur.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le client et le fournisseur pourront \u00e9ventuellement convenir de garanties \u00e9quivalentes.<\/span><\/p>\n<ol start=\"10\">\n<li><b> GARANTIE ET RESPONSABILIT\u00c9S<\/b><\/li>\n<li><span style=\"font-weight: 400;\">a) Etendue<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Le fournisseur garantit durant 1 an, soit le premier but atteint, une construction correcte, une qualit\u00e9 ad\u00e9quate des mat\u00e9riaux utilis\u00e9s et une ex\u00e9cution irr\u00e9prochable. Si le mat\u00e9riel fourni change de propri\u00e9taire avant l\u2019expiration du d\u00e9lai de garantie ordinaire, celle-ci prend fin au moment du transfert de propri\u00e9t\u00e9.<\/span><br \/>\n<span style=\"font-weight: 400;\">La garantie du fournisseur ne s\u2019applique pas :<\/span><br \/>\n<span style=\"font-weight: 400;\">\u2013 \u00e0 du mat\u00e9riel usag\u00e9 ou des pi\u00e8ces en faisant partie<\/span><br \/>\n<span style=\"font-weight: 400;\">\u2013 \u00e0 du mat\u00e9riel qu\u2019il n\u2019a pas fourni<\/span><br \/>\n<span style=\"font-weight: 400;\">\u2013 \u00e0 des travaux de montage ou de d\u00e9montage qui n\u2019ont pas \u00e9t\u00e9 effectu\u00e9s par lui, ainsi que pour des objets <\/span><span style=\"font-weight: 400;\">qui ont \u00e9t\u00e9 modifi\u00e9s ou r\u00e9par\u00e9s sans son accord.<\/span><br \/>\n<span style=\"font-weight: 400;\">\u2013 si le client a proc\u00e9d\u00e9 \u00e0 des modifications, notamment mont\u00e9 des \u00e9quipements suppl\u00e9mentaires sur le <\/span><span style=\"font-weight: 400;\">mat\u00e9riel.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u2013 \u00e0 des d\u00e9t\u00e9riorations de toute nature imputables \u00e0 une usure normale, \u00e0 un maniement erron\u00e9 ou violent,<\/span><br \/>\n<span style=\"font-weight: 400;\">\u00e0 des sollicitations excessives, \u00e0 des fondations insuffisantes, \u00e0 une utilisation et \u00e0 un entretien inad\u00e9quats,<\/span><br \/>\n<span style=\"font-weight: 400;\">au gel, \u00e0 l\u2019emploi de mat\u00e9riaux et de lubrifiants inappropri\u00e9s, \u00e0 des accidents ou \u00e0 des cas de force majeure<\/span><br \/>\n<span style=\"font-weight: 400;\">et \u00e0 des causes similaires.<\/span><br \/>\n<span style=\"font-weight: 400;\">\u2013 \u00e0 des articles ou du mat\u00e9riel qui ne sont pas de sa fabrication, tels que p. ex. \u00e9quipements \u00e9lectriques,<\/span><br \/>\n<span style=\"font-weight: 400;\">pneumatiques etc. pour lesquels le client ne pourra b\u00e9n\u00e9ficier que des garanties qui sont accord\u00e9es au<\/span><br \/>\n<span style=\"font-weight: 400;\">fournisseur par les fabricants respectifs.<\/span><br \/>\n<span style=\"font-weight: 400;\">\u2013 la garantie est strictement limit\u00e9e \u00e0 ce qui a \u00e9t\u00e9 \u00e9nonc\u00e9 pr\u00e9c\u00e9demment. En particulier, sont express\u00e9ment<\/span><br \/>\n<span style=\"font-weight: 400;\">exclues toutes autres ou plus amples pr\u00e9tentions (telles que diminution du prix ou r\u00e9siliation) ainsi que tout<\/span><br \/>\n<span style=\"font-weight: 400;\">autres dommages directs ou indirects du client (tels que ceux r\u00e9sultant de l\u2019impossibilit\u00e9 d\u2019utiliser le<\/span><br \/>\n<span style=\"font-weight: 400;\">mat\u00e9riel faisant l\u2019objet du contrat ou de la mise en cause du client en raison de dommages occasionn\u00e9s \u00e0<\/span><br \/>\n<span style=\"font-weight: 400;\">des tiers en relation avec la livraison et l\u2019exploitation de l\u2019objet du contrat). Cependant, cette limitation ne<\/span><br \/>\n<span style=\"font-weight: 400;\">s\u2019applique pas \u00e0 des dommages manifestement caus\u00e9s par une faute grave ou une intention frauduleuse du <\/span><span style=\"font-weight: 400;\">fournisseur.<\/p>\n<p><\/span>b) Droit de recours<\/p>\n<p><span style=\"font-weight: 400;\">Si le fournisseur est mis en cause par un tiers en raison d\u2019un dommage et qu\u2019il y a responsabilit\u00e9 solidaire,<\/span><br \/>\n<span style=\"font-weight: 400;\">il pourra exercer son recours contre le client pour tous ses frais, pour autant qu\u2019aucune faute grave de sa<\/span><br \/>\n<span style=\"font-weight: 400;\">part ne soit prouv\u00e9e.<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\">c) Prestations au titre de la garantie<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Les d\u00e9fauts qui, aux termes de la pr\u00e9sente garantie, doivent \u00eatre pris en charge par le fournisseur seront<\/span><br \/>\n<span style=\"font-weight: 400;\">\u00e9limin\u00e9s aussi rapidement que possible sans frais pour le client et les pi\u00e8ces concern\u00e9es remplac\u00e9es.<\/span><br \/>\n<span style=\"font-weight: 400;\">Les contr\u00f4les d\u2019exploitation par des monteurs du fournisseur que le client demanderait ne font pas partie<\/span><br \/>\n<span style=\"font-weight: 400;\">des prestations accord\u00e9es au titre de la garantie, mais seront factur\u00e9s.<\/span><\/p>\n<ol start=\"11\">\n<li><b> DROIT APPLICABLE<\/b><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Les contrats conclus sont soumis au droit suisse.<\/span><\/p>\n<ol start=\"12\">\n<li><b> LIEU D\u2019EX\u00c9CUTION ET FOR JUDICIAIRE<\/b><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Le si\u00e8ge du fournisseur est r\u00e9put\u00e9 \u00eatre le lieu d\u2019ex\u00e9cution de toutes les obligations d\u00e9coulant du pr\u00e9sent <\/span><span style=\"font-weight: 400;\">contrat.<\/span><br \/>\n<span style=\"font-weight: 400;\">Le for judiciaire pour tous les litiges d\u00e9coulant du pr\u00e9sent contrat est celui du si\u00e8ge du fournisseur.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">B\u00e2le, le 21 octobre 1998.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>G\u00c9N\u00c9RALIT\u00c9S Les conditions suivantes s\u2019appliquent \u00e0 toutes les livraisons et \u00e0 tous les travaux du fournisseur r\u00e9sultant d\u2019un contrat de vente ou d\u2019entreprise. D\u2019\u00e9ventuelles d\u00e9rogations ne sont valables que si elles ont \u00e9t\u00e9 convenues par \u00e9crit entre les parties contractantes. OFFRE a) Bases techniques Les caract\u00e9ristiques techniques figurant dans l\u2019offre font foi. Toute divergence importante [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-25","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conditions g\u00e9n\u00e9rales de r\u00e9paration - CHRONO Flex Suisse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.chronoflex.ch\/fr\/conditions-generales-de-reparation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conditions g\u00e9n\u00e9rales de r\u00e9paration - CHRONO Flex Suisse\" \/>\n<meta property=\"og:description\" content=\"G\u00c9N\u00c9RALIT\u00c9S Les conditions suivantes s\u2019appliquent \u00e0 toutes les livraisons et \u00e0 tous les travaux du fournisseur r\u00e9sultant d\u2019un contrat de vente ou d\u2019entreprise. D\u2019\u00e9ventuelles d\u00e9rogations ne sont valables que si elles ont \u00e9t\u00e9 convenues par \u00e9crit entre les parties contractantes. OFFRE a) Bases techniques Les caract\u00e9ristiques techniques figurant dans l\u2019offre font foi. Toute divergence importante [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.chronoflex.ch\/fr\/conditions-generales-de-reparation\/\" \/>\n<meta property=\"og:site_name\" content=\"CHRONO Flex Suisse\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-28T08:08:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.chronoflex.ch\\\/fr\\\/conditions-generales-de-reparation\\\/\",\"url\":\"https:\\\/\\\/www.chronoflex.ch\\\/fr\\\/conditions-generales-de-reparation\\\/\",\"name\":\"Conditions g\u00e9n\u00e9rales de r\u00e9paration - CHRONO Flex Suisse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.chronoflex.ch\\\/#website\"},\"datePublished\":\"2017-03-14T11:01:13+00:00\",\"dateModified\":\"2017-04-28T08:08:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.chronoflex.ch\\\/fr\\\/conditions-generales-de-reparation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.chronoflex.ch\\\/fr\\\/conditions-generales-de-reparation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.chronoflex.ch\\\/fr\\\/conditions-generales-de-reparation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.chronoflex.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conditions g\u00e9n\u00e9rales de r\u00e9paration\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.chronoflex.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.chronoflex.ch\\\/\",\"name\":\"CHRONO Flex Suisse\",\"description\":\"Flexibles hydrauliques sur site 24h\\\/7j\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.chronoflex.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conditions g\u00e9n\u00e9rales de r\u00e9paration - CHRONO Flex Suisse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.chronoflex.ch\/fr\/conditions-generales-de-reparation\/","og_locale":"fr_FR","og_type":"article","og_title":"Conditions g\u00e9n\u00e9rales de r\u00e9paration - CHRONO Flex Suisse","og_description":"G\u00c9N\u00c9RALIT\u00c9S Les conditions suivantes s\u2019appliquent \u00e0 toutes les livraisons et \u00e0 tous les travaux du fournisseur r\u00e9sultant d\u2019un contrat de vente ou d\u2019entreprise. D\u2019\u00e9ventuelles d\u00e9rogations ne sont valables que si elles ont \u00e9t\u00e9 convenues par \u00e9crit entre les parties contractantes. OFFRE a) Bases techniques Les caract\u00e9ristiques techniques figurant dans l\u2019offre font foi. Toute divergence importante [&hellip;]","og_url":"https:\/\/www.chronoflex.ch\/fr\/conditions-generales-de-reparation\/","og_site_name":"CHRONO Flex Suisse","article_modified_time":"2017-04-28T08:08:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.chronoflex.ch\/fr\/conditions-generales-de-reparation\/","url":"https:\/\/www.chronoflex.ch\/fr\/conditions-generales-de-reparation\/","name":"Conditions g\u00e9n\u00e9rales de r\u00e9paration - CHRONO Flex Suisse","isPartOf":{"@id":"https:\/\/www.chronoflex.ch\/#website"},"datePublished":"2017-03-14T11:01:13+00:00","dateModified":"2017-04-28T08:08:09+00:00","breadcrumb":{"@id":"https:\/\/www.chronoflex.ch\/fr\/conditions-generales-de-reparation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.chronoflex.ch\/fr\/conditions-generales-de-reparation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.chronoflex.ch\/fr\/conditions-generales-de-reparation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.chronoflex.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Conditions g\u00e9n\u00e9rales de r\u00e9paration"}]},{"@type":"WebSite","@id":"https:\/\/www.chronoflex.ch\/#website","url":"https:\/\/www.chronoflex.ch\/","name":"CHRONO Flex Suisse","description":"Flexibles hydrauliques sur site 24h\/7j","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.chronoflex.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.chronoflex.ch\/fr\/wp-json\/wp\/v2\/pages\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chronoflex.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.chronoflex.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.chronoflex.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chronoflex.ch\/fr\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":3,"href":"https:\/\/www.chronoflex.ch\/fr\/wp-json\/wp\/v2\/pages\/25\/revisions"}],"predecessor-version":[{"id":698,"href":"https:\/\/www.chronoflex.ch\/fr\/wp-json\/wp\/v2\/pages\/25\/revisions\/698"}],"wp:attachment":[{"href":"https:\/\/www.chronoflex.ch\/fr\/wp-json\/wp\/v2\/media?parent=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}