{"id":127,"date":"2017-03-30T09:46:25","date_gmt":"2017-03-30T07:46:25","guid":{"rendered":"http:\/\/www.chronoflex.ch\/?page_id=127"},"modified":"2022-07-15T15:02:17","modified_gmt":"2022-07-15T13:02:17","slug":"clinique-du-flex","status":"publish","type":"page","link":"https:\/\/www.chronoflex.ch\/fr\/nos-services\/clinique-du-flex\/","title":{"rendered":"Clinique du Flex"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; module_class=\u00a0\u00bbflex-center\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb background_image=\u00a0\u00bbhttps:\/\/www.chronoflex.ch\/\/wp-content\/uploads\/2017\/04\/11.04.16-1.jpg\u00a0\u00bb height=\u00a0\u00bb40vh\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb positioning=\u00a0\u00bbabsolute\u00a0\u00bb position_origin_a=\u00a0\u00bbcenter_center\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb header_text_align=\u00a0\u00bbright\u00a0\u00bb header_text_color=\u00a0\u00bb#004588&Prime; background_color=\u00a0\u00bb#FFFFFF\u00a0\u00bb positioning=\u00a0\u00bbabsolute\u00a0\u00bb position_origin_a=\u00a0\u00bbcenter_center\u00a0\u00bb custom_padding=\u00a0\u00bb1%|5%|0%|5%|false|false\u00a0\u00bb border_width_bottom=\u00a0\u00bb3px\u00a0\u00bb border_color_bottom=\u00a0\u00bb#ab0f15&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h1 style=\"text-align: center;\"><strong>La Clinique du Flex<\/strong><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb3.22&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\"><strong>D\u00e9couvrez notre clinique du flex<\/strong><\/h2>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"text-align: center;\"><span>Gr\u00e2ce \u00e0 la Clinique du flex, qui est enti\u00e8rement \u00e9quip\u00e9e et personnalisable, vous allez pouvoir confectionner vos flexibles hydrauliques directement sur place en toute autonomie 24h\/7j et sur tous vos chantiers et\/ou ateliers.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_video src=\u00a0\u00bbhttps:\/\/youtu.be\/raCS-15GHtM\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb width=\u00a0\u00bb70%\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 style=\"text-align: center;\"><strong>Les avantages de la Clinique du Flex<\/strong><\/h2>\n<p style=\"text-align: center;\">Atelier mobile, \u00e9quip\u00e9 et personnalis\u00e9 pour la confection de vos flexibles en autonomie.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_3,1_3,1_3&Prime; _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_toggle title=\u00a0\u00bbSolution autonome\u00a0\u00bb open_toggle_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb closed_toggle_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_font=\u00a0\u00bb|700|||||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-10934ff7-b0f7-4779-a132-cf876bb4915e%22:%91%22closed_toggle_text_color%22,%22open_toggle_text_color%22%93}\u00a0\u00bb]<\/p>\n<p>Cellule de confection de flexibles s\u00e9curis\u00e9e, l\u00e9g\u00e8re, transportable, inalt\u00e9rable et autonome, \u00e9quip\u00e9e de machines de qualit\u00e9 : tron\u00e7onneuse, d\u00e9nudeuse, sertisseuse, sertisseuse manuelle, d\u00e9pollution des flexibles, ameublement, etc.<\/p>\n<p>Equip\u00e9e d\u2019un groupe \u00e9lectrique, elle est totalement autonomes en \u00e9nergie et peut \u00eatre positionn\u00e9e sur n\u2019importe quel type de chantier, m\u00eame les plus recul\u00e9s \u201cau milieu de nulle part\u201d<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=\u00a0\u00bb2 en 1&Prime; open_toggle_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb closed_toggle_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_font=\u00a0\u00bb|700|||||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-10934ff7-b0f7-4779-a132-cf876bb4915e%22:%91%22closed_toggle_text_color%22,%22open_toggle_text_color%22%93}\u00a0\u00bb]<\/p>\n<p>Notre Clinique du Flex a 2 avantages pour vous servir :<\/p>\n<p>Fixe : elle est \u00e0 votre disposition 24h\/7j, pos\u00e9e sur votre site, pr\u00eate \u00e0 \u00eatre utilis\u00e9e par vos \u00e9quipiers pour garantir la continuit\u00e9 de vos grands chantiers et de vos ateliers.<\/p>\n<p>Mobile : votre chantier se d\u00e9place g\u00e9ographiquement ? La Clinique du Flex aussi ! Dot\u00e9e d\u2019anneaux de levage \u00e0 ses 4 coins et d\u2019un passage de fourche \u00e0 sa base, elle peut \u00eatre transport\u00e9e \u00e0 l\u2019aide d\u2019une grue, d\u2019un chariot \u00e9l\u00e9vateur ou d\u2019autres engins de levage et manutention pour \u00eatre toujours au plus proche de vos besoins et de vos \u00e9quipes en action.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=\u00a0\u00bbFormation\u00a0\u00bb open_toggle_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb closed_toggle_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_font=\u00a0\u00bb|700|||||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-10934ff7-b0f7-4779-a132-cf876bb4915e%22:%91%22closed_toggle_text_color%22,%22open_toggle_text_color%22%93}\u00a0\u00bb]<\/p>\n<p>Pour devenir 100% autonome !<\/p>\n<p>Parce que la Clinique du Flex doit vous rendre autonome, notre r\u00e9f\u00e9rent formation national dispensera une formation th\u00e9orique et pratique d&rsquo;une journ\u00e9e enti\u00e8re.<\/p>\n<p>A l\u2019issue de la formation, nous pourrons ainsi valider les acquis et la bonne ma\u00eetrise des standards de la confection de A \u00e0 Z de flexibles hydrauliques par vos \u00e9quipiers afin de vous laisser 100% autonome sur cette nouvelle solution.<\/p>\n<p>En cas de besoin, nous restons \u00e0 vos c\u00f4t\u00e9s pour vous assurer la meilleure prise en main.<\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_toggle title=\u00a0\u00bbAvantages tarifaires\u00a0\u00bb open_toggle_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb closed_toggle_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_font=\u00a0\u00bb|700|||||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-10934ff7-b0f7-4779-a132-cf876bb4915e%22:%91%22closed_toggle_text_color%22,%22open_toggle_text_color%22%93}\u00a0\u00bb]<\/p>\n<p>La Clinique du Flex vous fait gagner en :<\/p>\n<p>-&gt; Autonomie : les comp\u00e9tences directement pr\u00e9sentes en interne<\/p>\n<p>-&gt; Co\u00fbts : fini les co\u00fbts impr\u00e9vus de demande d&rsquo;intervention urgente<\/p>\n<p>-&gt; Temps : Pas d&rsquo;attentes li\u00e9es aux d\u00e9placements<\/p>\n<p>En devenant autonome sur la r\u00e9alisation de vos flexibles, vous b\u00e9n\u00e9ficiez des meilleurs prix sur les pi\u00e8ces, tuyaux et accessoires gr\u00e2ce \u00e0 la tarification sp\u00e9cifique Chronoflex Pi\u00e8ces.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=\u00a0\u00bbEmpreinte carbone r\u00e9duite\u00a0\u00bb open_toggle_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb closed_toggle_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_font=\u00a0\u00bb|700|||||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-10934ff7-b0f7-4779-a132-cf876bb4915e%22:%91%22closed_toggle_text_color%22,%22open_toggle_text_color%22%93}\u00a0\u00bb]<\/p>\n<p>Au-del\u00e0 de l\u2019optimisation de vos co\u00fbts, la Clinique du Flex r\u00e9pond \u00e9galement aux enjeux RSE et de d\u00e9veloppement durable. Parce qu\u2019elle vous rend autonome, vous limitez vos d\u00e9placements entre vos chantiers et vos ateliers pour r\u00e9parer un flexible hydraulique au coup par coup.<\/p>\n<p>En plus de la r\u00e9activit\u00e9 imm\u00e9diate pour le d\u00e9pannage et la r\u00e9paration de vos flexibles, vous limitez ainsi votre empreinte carbone sur chacun de vos chantiers &amp; ateliers \u00e9quip\u00e9s de la Clinique du Flex.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=\u00a0\u00bbGestion de stock\u00a0\u00bb open_toggle_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb closed_toggle_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_font=\u00a0\u00bb|700|||||||\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; global_colors_info=\u00a0\u00bb{%22gcid-10934ff7-b0f7-4779-a132-cf876bb4915e%22:%91%22closed_toggle_text_color%22,%22open_toggle_text_color%22%93}\u00a0\u00bb sticky_enabled=\u00a0\u00bb0&Prime;]<\/p>\n<p>Sur vos chantiers, ou au sein de vos ateliers, vous utilisez souvent les m\u00eames engins et donc ce sont souvent les m\u00eames flexibles qui cassent ? L\u2019\u00e9quipe de Chronoflex analyse avec vous, en amont du projet, vos consommations potentielles sur les tuyaux, jupes, embouts, raccords, accessoires hydrauliques afin de pr\u00e9voir le stock n\u00e9cessaire pour r\u00e9pondre \u00e0 vos besoins.<\/p>\n<p>L\u2019application Chronoflex, install\u00e9e sur votre tablette, pourra g\u00e9rer ainsi les r\u00e9approvisionnements de mani\u00e8re automatique, vos commandes additionnelles, vos stocks tampons et retrouver la trace de toutes vos consommations.<\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_3&Prime; _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_toggle title=\u00a0\u00bbInvestissement\u00a0\u00bb open_toggle_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb closed_toggle_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_font=\u00a0\u00bb|700|||||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-10934ff7-b0f7-4779-a132-cf876bb4915e%22:%91%22closed_toggle_text_color%22,%22open_toggle_text_color%22%93}\u00a0\u00bb]<\/p>\n<p>Autonome, optimis\u00e9e, rentable, la Clinique du Flex est \u00e9galement flexible !<br \/>Votre besoin ne concerne qu\u2019un seul chantier\/atelier ? ou bien plusieurs ? ou il n\u00e9cessite une installation sur le long terme ?<\/p>\n<p>A chaque besoin, sa solution :<\/p>\n<p>-&gt; La location de votre Clinique du Flex est la meilleure solution pour vous !<br \/>-&gt; Nous livrons votre cellule \u00e0 l\u2019emplacement choisi par vos soins,<br \/>le stock ainsi que<br \/>-&gt; Une fois votre chantier termin\u00e9, ou bien l&rsquo;activit\u00e9 de votre atelier finie, la location s\u2019arr\u00eate et nous nous occupons du rapatriement de la cellule.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=\u00a0\u00bbUne solution rentable\u00a0\u00bb open_toggle_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb closed_toggle_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_font=\u00a0\u00bb|700|||||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-10934ff7-b0f7-4779-a132-cf876bb4915e%22:%91%22closed_toggle_text_color%22,%22open_toggle_text_color%22%93}\u00a0\u00bb]<\/p>\n<p>Avec un tr\u00e8s faible investissement de d\u00e9part, la rentabilit\u00e9 se fera rapidement ressentir dans votre porte-monnaie apr\u00e8s les premiers flexibles que vous aurez confectionn\u00e9s dans la cabine.<\/p>\n<p>[\/et_pb_toggle][et_pb_toggle title=\u00a0\u00bbService apr\u00e8s vente\u00a0\u00bb open_toggle_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb closed_toggle_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_font=\u00a0\u00bb|700|||||||\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-10934ff7-b0f7-4779-a132-cf876bb4915e%22:%91%22closed_toggle_text_color%22,%22open_toggle_text_color%22%93}\u00a0\u00bb]<\/p>\n<p>Un suivi op\u00e9rationnel, commercial et technique sera assur\u00e9 par un interlocuteur unique et privil\u00e9gi\u00e9, afin de vous accompagner et de rester \u00e0 votre disposition.<\/p>\n<p>[\/et_pb_toggle][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00a0\u00bb1_6,1_6,1_6,1_6,1_6,1_6&Prime; _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb max_width=\u00a0\u00bbnone\u00a0\u00bb module_alignment=\u00a0\u00bbcenter\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb1_6&Prime; _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_number_counter title=\u00a0\u00bbVolume en m3&Prime; number=\u00a0\u00bb13&Prime; percent_sign=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_text_align=\u00a0\u00bbcenter\u00a0\u00bb title_text_color=\u00a0\u00bb#000000&Prime; number_font=\u00a0\u00bb|700|||||||\u00a0\u00bb number_text_align=\u00a0\u00bbcenter\u00a0\u00bb number_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb number_font_size=\u00a0\u00bb4em\u00a0\u00bb custom_margin=\u00a0\u00bb|0px||0px|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|0px||0px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-10934ff7-b0f7-4779-a132-cf876bb4915e%22:%91%22number_text_color%22%93}\u00a0\u00bb][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_6&Prime; _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_number_counter title=\u00a0\u00bbLongueur int\u00e9rieur en mm\u00a0\u00bb number=\u00a0\u00bb3430&Prime; percent_sign=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_text_align=\u00a0\u00bbcenter\u00a0\u00bb title_text_color=\u00a0\u00bb#000000&Prime; number_font=\u00a0\u00bb|700|||||||\u00a0\u00bb number_text_align=\u00a0\u00bbcenter\u00a0\u00bb number_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb number_font_size=\u00a0\u00bb4em\u00a0\u00bb custom_margin=\u00a0\u00bb||||false|false\u00a0\u00bb custom_padding=\u00a0\u00bb||||false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-10934ff7-b0f7-4779-a132-cf876bb4915e%22:%91%22number_text_color%22,%22number_text_color%22%93}\u00a0\u00bb][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_6&Prime; _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_number_counter title=\u00a0\u00bbLargeur int\u00e9rieur en mm\u00a0\u00bb number=\u00a0\u00bb1960&Prime; percent_sign=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_text_align=\u00a0\u00bbcenter\u00a0\u00bb title_text_color=\u00a0\u00bb#000000&Prime; number_font=\u00a0\u00bb|700|||||||\u00a0\u00bb number_text_align=\u00a0\u00bbcenter\u00a0\u00bb number_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb number_font_size=\u00a0\u00bb4em\u00a0\u00bb custom_margin=\u00a0\u00bb|0px||0px|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|0px||0px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-10934ff7-b0f7-4779-a132-cf876bb4915e%22:%91%22number_text_color%22,%22number_text_color%22%93}\u00a0\u00bb][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_6&Prime; _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_number_counter title=\u00a0\u00bbHauteur int\u00e9rieur en mm\u00a0\u00bb number=\u00a0\u00bb1960&Prime; percent_sign=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_text_align=\u00a0\u00bbcenter\u00a0\u00bb title_text_color=\u00a0\u00bb#000000&Prime; number_font=\u00a0\u00bb|700|||||||\u00a0\u00bb number_text_align=\u00a0\u00bbcenter\u00a0\u00bb number_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb number_font_size=\u00a0\u00bb4em\u00a0\u00bb custom_margin=\u00a0\u00bb|0px||0px|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|0px||0px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-10934ff7-b0f7-4779-a132-cf876bb4915e%22:%91%22number_text_color%22,%22number_text_color%22,%22number_text_color%22%93}\u00a0\u00bb][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_6&Prime; _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_number_counter title=\u00a0\u00bbPoids en kg\u00a0\u00bb number=\u00a0\u00bb425&Prime; percent_sign=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_text_align=\u00a0\u00bbcenter\u00a0\u00bb title_text_color=\u00a0\u00bb#000000&Prime; number_font=\u00a0\u00bb|700|||||||\u00a0\u00bb number_text_align=\u00a0\u00bbcenter\u00a0\u00bb number_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb number_font_size=\u00a0\u00bb4em\u00a0\u00bb custom_margin=\u00a0\u00bb|0px||0px|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|0px||0px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-10934ff7-b0f7-4779-a132-cf876bb4915e%22:%91%22number_text_color%22,%22number_text_color%22,%22number_text_color%22%93}\u00a0\u00bb][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=\u00a0\u00bb1_6&Prime; _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_number_counter title=\u00a0\u00bbCharge utile en kg\u00a0\u00bb number=\u00a0\u00bb1300&Prime; percent_sign=\u00a0\u00bboff\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_text_align=\u00a0\u00bbcenter\u00a0\u00bb title_text_color=\u00a0\u00bb#000000&Prime; number_font=\u00a0\u00bb|700|||||||\u00a0\u00bb number_text_align=\u00a0\u00bbcenter\u00a0\u00bb number_text_color=\u00a0\u00bbgcid-10934ff7-b0f7-4779-a132-cf876bb4915e\u00a0\u00bb number_font_size=\u00a0\u00bb4em\u00a0\u00bb custom_margin=\u00a0\u00bb|0px||0px|false|false\u00a0\u00bb custom_padding=\u00a0\u00bb|0px||0px|false|false\u00a0\u00bb global_colors_info=\u00a0\u00bb{%22gcid-10934ff7-b0f7-4779-a132-cf876bb4915e%22:%91%22number_text_color%22,%22number_text_color%22,%22number_text_color%22%93}\u00a0\u00bb][\/et_pb_number_counter][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_button button_text=\u00a0\u00bbContactez-nous\u00a0\u00bb _builder_version=\u00a0\u00bb4.14.7&Prime; _module_preset=\u00a0\u00bb3d393a71-91b7-4b17-a5ca-30d9ea7bfa4d\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De par sa mobilit\u00e9, la Clinique du Flex\u2019 vous accompagne sur tous vos chantiers et sera au plus pr\u00e8s de vos besoins de r\u00e9parations de flexibles hydrauliques. Elle est transportable facilement gr\u00e2ce \u00e0 ses fixations.<\/p>\n","protected":false},"author":1,"featured_media":699,"parent":3282,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/raCS-15GHtM\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe>\r\n\r\n<strong>Mobilit\u00e9 et Accessibilit\u00e9<\/strong>\r\n\r\nDe par sa mobilit\u00e9, la Clinique du Flex\u2019 vous accompagne sur tous vos chantiers et sera au plus pr\u00e8s de vos besoins de r\u00e9parations de flexibles hydrauliques. Elle est facilement\u00a0transportable gr\u00e2ce \u00e0 ses fixations.\r\n\r\n<strong>Personnalisation<\/strong>\r\n\r\nNous effectuons un tour de parc de vos machines avant l\u2019installation de la clinique qui sera ainsi \u00e9quip\u00e9 de pi\u00e8ces et de flexibles adapt\u00e9s \u00e0 vos besoins.\r\nAvec son syst\u00e8me d\u2019accroches m\u00e2les et femelles, il est \u00e9galement possible de coupler 2 Cliniques.\r\n\r\n<strong>Autonomie et Gain de temps<\/strong>\r\n\r\nVotre technicien form\u00e9 au pr\u00e9alable par nos soins \u00e0 la confection du flexible hydraulique pourra \u00e0 tout moment changer le flexible pour limiter le temps d\u2019immobilisation de la machine et ainsi gagner du temps pr\u00e9cieux et avoir une meilleure gestion des co\u00fbts (immobilisation machines, retard sur chantier...)\r\n\r\n<strong>Outils (\u00e0 la demande)<\/strong>\r\n\r\nSertisseuse, tron\u00e7onneuse, d\u00e9nudeuse, kit de d\u00e9pollution flexible, g\u00e9n\u00e9ratrice ... on rajoute l\u2019outillage \u00e0 votre demande (permet l\u2019autonomie du conteneur). La livraison de vos pi\u00e8ces se fait en 48h.\r\n\r\n<strong>Commander \u00e0 distance<\/strong>\r\n\r\nIl vous est possible de g\u00e9rer votre stock par PDA ce qui permet une automatisation des commandes selon des seuils mini\/maxi qui seront d\u00e9fini en amont. Vous avez aussi la possibilit\u00e9 de prendre des photos des pannes en cas de :\r\n<ul>\r\n \t<li>casse : imput\u00e9 le co\u00fbt sur le budget du chantier<\/li>\r\n \t<li>usure : pas d\u2019imputation sur le budget du chantier<\/li>\r\n<\/ul>\r\n<strong>Capacit\u00e9 du stock<\/strong>\r\n<ul>\r\n \t<li>300 m\u00e8tres de flexibles, et plus si besoin<\/li>\r\n \t<li>Diam\u00e8tre 1\/4 au 1\u20191\/4<\/li>\r\n<\/ul>\r\n<strong>L\u00e9g\u00e8re et robuste<\/strong>\r\n<ul>\r\n \t<li>Forte r\u00e9sistance aux chocs<\/li>\r\n \t<li>Structure garantie 8 ans<\/li>\r\n \t<li>R\u00e9sistance des rangements : gr\u00e2ce \u00e0 des tiroirs<\/li>\r\n<\/ul>\r\n<strong>Transportable<\/strong>\r\n<ul>\r\n \t<li>Prises \u00e9lingues, 4 c\u00f4t\u00e9s<\/li>\r\n \t<li>Prise fourche, chariot \u00e9l\u00e9vateur<\/li>\r\n<\/ul>\r\n<strong>Innovante et design<\/strong>\r\n<ul>\r\n \t<li>Technique de l\u2019infusion : injection de r\u00e9sine sous vide<\/li>\r\n \t<li>Cellule monobloc<\/li>\r\n \t<li>Lisse, sans aluminium d\u2019assemblage<\/li>\r\n<\/ul>\r\n<strong>Modulable<\/strong>\r\n<ul>\r\n \t<li>Am\u00e9nagement int\u00e9rieur sp\u00e9cialis\u00e9 et professionnel pour la confection de flexibles hydrauliques, similaire \u00e0 un atelier.<\/li>\r\n<\/ul>\r\n\u00a0\r\n\r\n\u00a0\r\n\r\n\u00a0\r\n<h2><\/h2>","_et_gb_content_width":"","footnotes":""},"class_list":["post-127","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Clinique du Flex - CHRONO Flex Suisse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.chronoflex.ch\/fr\/nos-services\/clinique-du-flex\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Clinique du Flex - CHRONO Flex Suisse\" \/>\n<meta property=\"og:description\" content=\"De par sa mobilit\u00e9, la Clinique du Flex\u2019 vous accompagne sur tous vos chantiers et sera au plus pr\u00e8s de vos besoins de r\u00e9parations de flexibles hydrauliques. Elle est transportable facilement gr\u00e2ce \u00e0 ses fixations.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.chronoflex.ch\/fr\/nos-services\/clinique-du-flex\/\" \/>\n<meta property=\"og:site_name\" content=\"CHRONO Flex Suisse\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-15T13:02:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.chronoflex.ch\/wp-content\/uploads\/2017\/04\/11.04.16-1-1024x768.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.chronoflex.ch\\\/fr\\\/nos-services\\\/clinique-du-flex\\\/\",\"url\":\"https:\\\/\\\/www.chronoflex.ch\\\/fr\\\/nos-services\\\/clinique-du-flex\\\/\",\"name\":\"Clinique du Flex - CHRONO Flex Suisse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.chronoflex.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.chronoflex.ch\\\/fr\\\/nos-services\\\/clinique-du-flex\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.chronoflex.ch\\\/fr\\\/nos-services\\\/clinique-du-flex\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.chronoflex.ch\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/11.04.16-1.jpg\",\"datePublished\":\"2017-03-30T07:46:25+00:00\",\"dateModified\":\"2022-07-15T13:02:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.chronoflex.ch\\\/fr\\\/nos-services\\\/clinique-du-flex\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.chronoflex.ch\\\/fr\\\/nos-services\\\/clinique-du-flex\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.chronoflex.ch\\\/fr\\\/nos-services\\\/clinique-du-flex\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.chronoflex.ch\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/11.04.16-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.chronoflex.ch\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/11.04.16-1.jpg\",\"width\":4032,\"height\":3024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.chronoflex.ch\\\/fr\\\/nos-services\\\/clinique-du-flex\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.chronoflex.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos services\",\"item\":\"https:\\\/\\\/www.chronoflex.ch\\\/fr\\\/nos-services\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Clinique du Flex\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.chronoflex.ch\\\/#website\",\"url\":\"https:\\\/\\\/www.chronoflex.ch\\\/\",\"name\":\"CHRONO Flex Suisse\",\"description\":\"Flexibles hydrauliques sur site 24h\\\/7j\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.chronoflex.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Clinique du Flex - CHRONO Flex Suisse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.chronoflex.ch\/fr\/nos-services\/clinique-du-flex\/","og_locale":"fr_FR","og_type":"article","og_title":"Clinique du Flex - CHRONO Flex Suisse","og_description":"De par sa mobilit\u00e9, la Clinique du Flex\u2019 vous accompagne sur tous vos chantiers et sera au plus pr\u00e8s de vos besoins de r\u00e9parations de flexibles hydrauliques. Elle est transportable facilement gr\u00e2ce \u00e0 ses fixations.","og_url":"https:\/\/www.chronoflex.ch\/fr\/nos-services\/clinique-du-flex\/","og_site_name":"CHRONO Flex Suisse","article_modified_time":"2022-07-15T13:02:17+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.chronoflex.ch\/wp-content\/uploads\/2017\/04\/11.04.16-1-1024x768.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.chronoflex.ch\/fr\/nos-services\/clinique-du-flex\/","url":"https:\/\/www.chronoflex.ch\/fr\/nos-services\/clinique-du-flex\/","name":"Clinique du Flex - CHRONO Flex Suisse","isPartOf":{"@id":"https:\/\/www.chronoflex.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.chronoflex.ch\/fr\/nos-services\/clinique-du-flex\/#primaryimage"},"image":{"@id":"https:\/\/www.chronoflex.ch\/fr\/nos-services\/clinique-du-flex\/#primaryimage"},"thumbnailUrl":"https:\/\/www.chronoflex.ch\/wp-content\/uploads\/2017\/04\/11.04.16-1.jpg","datePublished":"2017-03-30T07:46:25+00:00","dateModified":"2022-07-15T13:02:17+00:00","breadcrumb":{"@id":"https:\/\/www.chronoflex.ch\/fr\/nos-services\/clinique-du-flex\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.chronoflex.ch\/fr\/nos-services\/clinique-du-flex\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.chronoflex.ch\/fr\/nos-services\/clinique-du-flex\/#primaryimage","url":"https:\/\/www.chronoflex.ch\/wp-content\/uploads\/2017\/04\/11.04.16-1.jpg","contentUrl":"https:\/\/www.chronoflex.ch\/wp-content\/uploads\/2017\/04\/11.04.16-1.jpg","width":4032,"height":3024},{"@type":"BreadcrumbList","@id":"https:\/\/www.chronoflex.ch\/fr\/nos-services\/clinique-du-flex\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.chronoflex.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Nos services","item":"https:\/\/www.chronoflex.ch\/fr\/nos-services\/"},{"@type":"ListItem","position":3,"name":"Clinique du Flex"}]},{"@type":"WebSite","@id":"https:\/\/www.chronoflex.ch\/#website","url":"https:\/\/www.chronoflex.ch\/","name":"CHRONO Flex Suisse","description":"Flexibles hydrauliques sur site 24h\/7j","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.chronoflex.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.chronoflex.ch\/fr\/wp-json\/wp\/v2\/pages\/127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chronoflex.ch\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.chronoflex.ch\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.chronoflex.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chronoflex.ch\/fr\/wp-json\/wp\/v2\/comments?post=127"}],"version-history":[{"count":50,"href":"https:\/\/www.chronoflex.ch\/fr\/wp-json\/wp\/v2\/pages\/127\/revisions"}],"predecessor-version":[{"id":3935,"href":"https:\/\/www.chronoflex.ch\/fr\/wp-json\/wp\/v2\/pages\/127\/revisions\/3935"}],"up":[{"embeddable":true,"href":"https:\/\/www.chronoflex.ch\/fr\/wp-json\/wp\/v2\/pages\/3282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.chronoflex.ch\/fr\/wp-json\/wp\/v2\/media\/699"}],"wp:attachment":[{"href":"https:\/\/www.chronoflex.ch\/fr\/wp-json\/wp\/v2\/media?parent=127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}